{"id":3469,"date":"2016-01-27T16:38:50","date_gmt":"2016-01-27T21:38:50","guid":{"rendered":"http:\/\/memoire.mile-end.qc.ca\/?p=3469"},"modified":"2016-03-19T12:37:48","modified_gmt":"2016-03-19T16:37:48","slug":"les-soeurs-mcnulty-et-le-mile-end","status":"publish","type":"post","link":"http:\/\/memoire.mile-end.qc.ca\/fr\/les-soeurs-mcnulty-et-le-mile-end\/","title":{"rendered":"Les soeurs McNulty et le Mile End"},"content":{"rendered":"<p><\/p>\n<h4><span style=\"color: #339966;\"><em><span style=\"color: #008000;\">M\u00e9moire du Mile End tient \u00e0 remercier Vicky Robinson, la petite-fille de Marcella McNulty. Sans sa pr\u00e9cieuse collaboration, nous n&#8217;aurions pu retracer l&#8217;histoire de cette famille irlandaise du quartier.<\/span><\/em><\/span><\/h4>\n<p>L\u2019\u00e9dition 1911-1912 de l\u2019annuaire Lovell contient une inscription inhabituelle. Au rez-de-chauss\u00e9e d\u2019un triplex nouvellement construit, sur l\u2019avenue du Parc un peu au nord de la rue Bernard, du c\u00f4t\u00e9 est, r\u00e9sident les \u00ab McNulty Misses\u00bb. Habituellement, quand le chef de famille \u2013 la seule personne recens\u00e9e par l&#8217;annuaire \u2013 n\u2019est pas un homme, on pr\u00e9cise la plupart du temps qu\u2019il s\u2019agit d\u2019une veuve. Or, non seulement aucune des demoiselles n\u2019est veuve mais, lorsqu\u2019elles r\u00e9sidaient \u00e0 deux pas de l\u00e0, rue Hutchison, au nord de Saint-Viateur, l\u2019ann\u00e9e pr\u00e9c\u00e9dente, c\u2019est un homme, William McNulty, qui est d\u00e9crit comme le chef de famille.<\/p>\n<div id=\"attachment_3473\" style=\"width: 495px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-3473\" loading=\"lazy\" class=\" wp-image-3473\" src=\"http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/5012940474_fa1b62c28d_o.jpg\" alt=\"\u00abThe McNulty Misses\u00bb. Quatre des s\u0153urs McNulty, devant leur logement du 2567 avenue du Parc, vers 1911-1915. Marcella se trouve \u00e0 l\u2019extr\u00eame-gauche et Babe, \u00e0 l\u2019extr\u00eame-droite. Charles Fox se trouve au milieu, \u00e0 la gauche de sa femme, Annie. La quatri\u00e8me s\u0153ur, Louise, se trouve \u00e0 la droite de Marcella. Collection Vicky Robinson. \" width=\"485\" height=\"471\" \/><p id=\"caption-attachment-3473\" class=\"wp-caption-text\">\u00ab The McNulty Misses \u00bb. Quatre des s\u0153urs McNulty, devant leur logement du 2567 avenue du Parc, vers 1911-1915. Marcella se trouve \u00e0 l\u2019extr\u00eame-gauche et Babe, \u00e0 l\u2019extr\u00eame-droite. Charles Fox se trouve au milieu, \u00e0 la gauche de sa femme, Annie. La quatri\u00e8me s\u0153ur, Louise, se trouve \u00e0 la droite de Marcella. Collection Vicky Robinson.<\/p><\/div>\n<div id=\"attachment_3476\" style=\"width: 228px\" class=\"wp-caption alignright\"><img aria-describedby=\"caption-attachment-3476\" loading=\"lazy\" class=\"wp-image-3476 \" src=\"http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Parc-et-Bernard-ete-V.-Robison-150x150.jpg\" alt=\"Le triplex de l'avenue du Parc, au nord de Bernard, aujourd'hui disparu. Les soeurs McNulty y emm\u00e9nagent en 1911. Collection Vicky Robinson.\" width=\"218\" height=\"218\" \/><p id=\"caption-attachment-3476\" class=\"wp-caption-text\">Le triplex de l&#8217;avenue du Parc, au nord de Bernard, aujourd&#8217;hui disparu. Les soeurs McNulty y emm\u00e9nagent en 1911. Collection Vicky Robinson.<\/p><\/div>\n<p>Les parents des demoiselles McNulty, Thomas et Elizabeth sont arriv\u00e9s d\u2019Irlande pendant les ann\u00e9es 1860. Thomas devient policier \u00e0 la ville de Montr\u00e9al en 1879 et ils ont neuf enfants. Sept survivent, dont un seul fils, William. Elizabeth d\u00e9c\u00e8de, des suites de la grippe, fin avril 1901. On retrouve son mari mort sur la voie ferr\u00e9e, \u00e9cras\u00e9 par un train, \u00e0 peine cinq jours plus tard. La famille, inqui\u00e8te de ne pas l\u2019avoir vu rentrer \u00e0 la maison la veille, avait alert\u00e9 ses coll\u00e8gues. <em>The Gazette<\/em> \u00e9crit qu\u2019il s\u2019est probablement suicid\u00e9, en raison du chagrin caus\u00e9 par le d\u00e9c\u00e8s de son \u00e9pouse<a name=\"foot_loc_3469_1\" class=\"annie_footnoteRef annie_custom\" title=\"\u00ab Constable McNulty Killed by a Freight Train. Death of His Wife, and Recent Illness, It Is Thought, Might Have Preyed on Him \u00bb, The Gazette, 6 mai 1901\" href=\"http:\/\/memoire.mile-end.qc.ca\/fr\/les-soeurs-mcnulty-et-le-mile-end\/#foot_text_3469_1\">1<\/a>. Il appartient alors \u00e0 l&#8217;a\u00een\u00e9e, Annie, une c\u00e9libataire \u00e2g\u00e9e de 26 ans, de devenir la chef de famille. Celui que le recenseur du Lovell consid\u00e8re comme le chef, m\u0153urs de l\u2019\u00e9poque oblige, est son jeune fr\u00e8re de 20 ans, William. Ses s\u0153urs diront qu\u2019il r\u00eavait de devenir m\u00e9decin, mais le d\u00e9c\u00e8s de ses parents l\u2019oblige \u00e0 se trouver tout de suite un emploi, d\u2019abord comme machiniste et ensuite comme \u00e9lectricien. Annie, pour sa part, est t\u00e9l\u00e9phoniste.<\/p>\n<p>Au moment du d\u00e9c\u00e8s de leurs parents, les deux plus jeunes s\u0153urs, Marcella et Jemina \u2013\u2013que tout le monde appelle \u00ab Babe \u00bb, ont 18 et 16 ans. Elles ont la la r\u00e9putation d\u2019\u00eatre ind\u00e9pendantes et fougueuses\u00a0; l\u2019a\u00een\u00e9e, raconteront-elles beaucoup plus tard, menait la maisonn\u00e9e d\u2019une main de fer et imposait une forte discipline. Au moment de son d\u00e9c\u00e8s, en 1936, Annie McNulty \u00e9tait d\u2019ailleurs devenue assistante-directrice de la prison pour femmes de Montr\u00e9al. En 1909, toute la famille quitte le vieux logement de la rue Cadieux (de Bullion aujourd\u2019hui) pour s\u2019installer dans un triplex flambant neuf, du c\u00f4t\u00e9 Outremont de la rue Hutchison.<\/p>\n<div id=\"attachment_3474\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-3474\" loading=\"lazy\" class=\"size-medium wp-image-3474\" src=\"http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Rue-Hutchison-v.1910-Robinson-600x542.jpg\" alt=\"Marcella McNulty, sur le trottoir situ\u00e9 du c\u00f4t\u00e9 ouest de la rue Hutchison, probablement devant le triplex o\u00f9 r\u00e9side alors la famille, vers 1910. L'\u00e9glise de l'Ascension, avenue du Parc, est en arri\u00e8re-plan. Collection Vicky Robinson. \" width=\"600\" height=\"542\" srcset=\"http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Rue-Hutchison-v.1910-Robinson-600x542.jpg 600w, http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Rue-Hutchison-v.1910-Robinson-768x693.jpg 768w, http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Rue-Hutchison-v.1910-Robinson.jpg 997w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-3474\" class=\"wp-caption-text\">Marcella McNulty, sur le trottoir situ\u00e9 du c\u00f4t\u00e9 ouest de la rue Hutchison, probablement devant le triplex o\u00f9 r\u00e9side alors la famille, vers 1910. L&#8217;\u00e9glise de l&#8217;Ascension, avenue du Parc, est en arri\u00e8re-plan.\u00a0Collection Vicky Robinson.<\/p><\/div>\n<div id=\"attachment_3477\" style=\"width: 538px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-3477\" loading=\"lazy\" class=\"size-full wp-image-3477\" src=\"http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Triplex-av.-du-Parc-arriere-V.-Robinson.jpg\" alt=\"Babe McNulty, sur le balcon arri\u00e8re du logement de l\u2019avenue du Parc, vers 1911-1915. Collection Vicky Robinson. \" width=\"528\" height=\"480\" \/><p id=\"caption-attachment-3477\" class=\"wp-caption-text\">Babe McNulty, sur le balcon arri\u00e8re du logement de l\u2019avenue du Parc, vers 1911-1915. Collection Vicky Robinson.<\/p><\/div>\n<p>Marcella et Babe acqui\u00e8rent leur libert\u00e9 l\u2019ann\u00e9e suivante, lorsque leur s\u0153ur a\u00een\u00e9e \u00e9pouse un veuf qui a vingt ans de plus qu\u2019elle. Il s\u2019agit de Charles James Fox, g\u00e9rant de la publicit\u00e9 au journal <em>The Gazette<\/em>. Tous deux Anglicans, ils se sont peut-\u00eatre connus comme paroissiens de la toute proche \u00e9glise de l\u2019Ascension, ouverte cinq ans plus t\u00f4t sur l&#8217;avenue du Parc, juste au sud de la rue Saint-Viateur. Apr\u00e8s leur mariage, Charles et Annie emm\u00e9nagent non loin, boulevard Saint-Joseph, tandis que Marcella et Babe laissent le logement de la rue Hutchison \u00e0 leur fr\u00e8re William, qui se marie lui aussi en 1910. Elles se trouvent un nouveau logement dans un autre triplex qui vient tout juste d\u2019\u00eatre construit, au 2567 avenue du Parc (ce serait le 5887 aujourd\u2019hui). Marcella et Babe sont alors toutes deux st\u00e9nographes, l&#8217;une pour un avocat et l&#8217;autre pour un marchand. Les fr\u00e8res Robinson, John et Garnett, vivent au rez-de-chauss\u00e9e du triplex adjacent. Apr\u00e8s une cour de quelques ann\u00e9es, ils r\u00e9ussissent \u00e0 s\u00e9duire chacun une s\u0153ur. Apr\u00e8s leurs mariages, en septembre 1915, les deux familles connaissent la vie typique des locataires montr\u00e9alais et d\u00e9m\u00e9nagent \u00e0 plusieurs reprises, \u00e0 la recherche de logements moins chers ou plus vastes. La g\u00e9n\u00e9ration suivante s\u2019installera \u00e0 Rosemont dans les ann\u00e9es d\u2019apr\u00e8s-guerre. Apr\u00e8s le d\u00e9c\u00e8s de Marcella, en 1978, sa petite-fille Vicky va retrouver des n\u00e9gatifs oubli\u00e9s dans un coffre qui lui appartenait. Cette d\u00e9couverte nous donne de tr\u00e8s rares t\u00e9moignages photographiques d&#8217;une famille irlandaise du Mile End et des rues du quartier, au d\u00e9but du 20<sup>\u00e8me<\/sup> si\u00e8cle.<\/p>\n<div id=\"attachment_3478\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-3478\" loading=\"lazy\" class=\"size-medium wp-image-3478\" src=\"http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Hutchison-ou-Parc-600x437.jpg\" alt=\"Le chien des McNulty, vers 1910. On aper\u00e7oit le c\u00f4t\u00e9 ouest de la rue Hutchison et la rue Durocher, ainsi que le mont Royal, en arri\u00e8re-plan. Les photos de triplex en construction, pendant cette p\u00e9riode, sont tr\u00e8s rares. Collection Vicky Robinson. \" width=\"600\" height=\"437\" srcset=\"http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Hutchison-ou-Parc-600x437.jpg 600w, http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Hutchison-ou-Parc-768x559.jpg 768w, http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Hutchison-ou-Parc.jpg 1024w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-3478\" class=\"wp-caption-text\">Le chien des McNulty, vers 1910. On aper\u00e7oit le c\u00f4t\u00e9 ouest de la rue Hutchison et la rue Durocher, ainsi que le mont Royal, en arri\u00e8re-plan. Les photos de triplex en construction, pendant cette p\u00e9riode, sont tr\u00e8s rares. Collection Vicky Robinson.<\/p><\/div>\n<div id=\"attachment_3481\" style=\"width: 575px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-3481\" loading=\"lazy\" class=\" wp-image-3481\" src=\"http:\/\/memoire.mile-end.qc.ca\/wp-content\/uploads\/Avenue-du-Parc-nord-de-Bernard-v.-1910-V.-Robinson.jpg\" alt=\"Marcella McNulty, devant le triplex de l'avenue du Parc, entre 1911 et 1915. Collection Vicky Robinson.\" width=\"565\" height=\"342\" \/><p id=\"caption-attachment-3481\" class=\"wp-caption-text\">Marcella McNulty, devant le triplex de l&#8217;avenue du Parc, entre 1911 et 1915. Collection Vicky Robinson.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>M\u00e9moire du Mile End tient \u00e0 remercier Vicky Robinson, la petite-fille de Marcella McNulty. Sans sa pr\u00e9cieuse collaboration, nous n&#8217;aurions pu retracer l&#8217;histoire de cette famille irlandaise du quartier. L\u2019\u00e9dition 1911-1912 de l\u2019annuaire Lovell contient une inscription inhabituelle. Au rez-de-chauss\u00e9e d\u2019un triplex nouvellement construit, sur l\u2019avenue du Parc un peu au nord de la rue [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[32],"_links":{"self":[{"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/posts\/3469"}],"collection":[{"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/comments?post=3469"}],"version-history":[{"count":14,"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/posts\/3469\/revisions"}],"predecessor-version":[{"id":3539,"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/posts\/3469\/revisions\/3539"}],"wp:attachment":[{"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/media?parent=3469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/categories?post=3469"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/memoire.mile-end.qc.ca\/fr\/wp-json\/wp\/v2\/tags?post=3469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}